{"id":1119,"date":"2015-09-18T16:00:00","date_gmt":"2015-09-18T16:00:00","guid":{"rendered":"http:\/\/optimalbrain.ch\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/"},"modified":"2015-09-18T16:00:00","modified_gmt":"2015-09-18T16:00:00","slug":"funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang","status":"publish","type":"post","link":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/","title":{"rendered":"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang"},"content":{"rendered":"<p>In den letzten Jahren hat die Paleo-Di\u00e4t als Mittel zur Verbesserung der allgemeinen Gesundheit viel Aufmerksamkeit erhalten. Die anekdotische Evidenz f\u00fcr die Verbesserung der Patienten durch eine Paleo-Di\u00e4t oder die restriktivere Autoimmun-Paleo-Di\u00e4t (AIP) ist reichlich vorhanden<sup data-preserve-html-node=\"true\">.1-5<\/sup><\/p>\n<p>Was man seltener h\u00f6rt, ist, dass manche Menschen negative Auswirkungen oder eine Verschlimmerung ihrer Symptome mit einer Paleo- oder AIP-Di\u00e4t erleben. Es scheint kontraintuitiv, dass eine gesunde Ern\u00e4hrung mit einem hohen Anteil an Kreuzbl\u00fctlern wie Gr\u00fcnkohl, Kohl und Brokkoli in Kombination mit hochwertigen Proteinen und Fetten dazu f\u00fchren kann, dass man sich schlechter f\u00fchlt. Warum ist das der Fall? Eine Hypothese besagt, dass Menschen, die sich mit einer Paleo- oder AIP-Di\u00e4t nicht besser f\u00fchlen, m\u00f6glicherweise ein Problem mit der Verarbeitung von Schwefel haben.<\/p>\n<p>Schwefel ist f\u00fcr verschiedene physiologische Funktionen in unserem K\u00f6rper unentbehrlich und hat in der Regel einen positiven Einfluss auf unsere Gesundheit. So kann Schwefel beispielsweise die Entgiftungsf\u00e4higkeit des K\u00f6rpers erheblich verbessern und das Immunsystem dabei unterst\u00fctzen, angemessen auf gef\u00e4hrliche Krankheitserreger zu reagieren. Schwefel ist auch wichtig f\u00fcr die Hormon- und Wasserregulierung, das Gleichgewicht des Mikrobioms in Ihrem Darm und die Unterst\u00fctzung eines gesunden Bindegewebes<sup data-preserve-html-node=\"true\">.6<\/sup><\/p>\n<p>Wenn sich Schwefel im K\u00f6rper anreichert, kann dies zu einer Vielzahl von scheinbar unerkl\u00e4rlichen Symptomen und Ungleichgewichten f\u00fchren. Ein \u00dcberschuss an Schwefel wird mit einer Dysbiose in Verbindung gebracht, die es pathogenen Bakterien im Darm erm\u00f6glicht, sich in ungesundem Ma\u00dfe zu vermehren. Au\u00dferdem kann es zu einem BH4-Verlust kommen, der das Gleichgewicht wichtiger Gehirnchemikalien wie Dopamin und Serotonin st\u00f6rt. Angstzust\u00e4nde, Depressionen, Kopfschmerzen und andere unerw\u00fcnschte Nebenwirkungen treten h\u00e4ufig auf, wenn diese Chemikalien aus dem Gleichgewicht geraten sind<sup data-preserve-html-node=\"true\">.7<\/sup><\/p>\n<p>Ein Grund f\u00fcr hohe Schwefelwerte kann sein, dass Sie \u00fcberm\u00e4\u00dfige Mengen an Schwefel \u00fcber Lebensmittel oder Nahrungserg\u00e4nzungsmittel zu sich nehmen. Ein wahrscheinlicherer Grund ist jedoch, dass Sie einen Defekt in Ihrem Transsulfurierungsweg haben, der dazu f\u00fchrt, dass Sie Schwefel nicht richtig verarbeiten k\u00f6nnen. Die Ursache f\u00fcr diesen Defekt kann eine toxische Exposition gegen\u00fcber Schwermetallen und Pestiziden wie Aluminium, Cadmium und Glyphosat sein. Eine weitere Ursache kann sein, dass Ihrem K\u00f6rper die f\u00fcr die Verarbeitung von Schwefel notwendigen N\u00e4hrstoffe wie B6 und Molybd\u00e4n fehlen. Nach meiner klinischen Erfahrung sind die h\u00e4ufigsten Verursacher genetische Mutationen, die den Transsulfurierungsweg betreffen<sup data-preserve-html-node=\"true\">.8<\/sup><\/p>\n<h2>Woher wissen Sie also, ob Sie m\u00f6glicherweise ein Problem mit der Verarbeitung von Schwefel haben?<\/h2>\n<p>Einige wichtige \u00dcberlegungen sind:<\/p>\n<ul>\n<li>Haben Sie jemals Reaktionen auf Medikamente auf Sulfa-Basis erlebt?<\/li>\n<li>Leiden Sie in der Vergangenheit an Asthma und Kurzatmigkeit?<\/li>\n<li>Sind Sie aufgebl\u00e4ht, haben Sie Bl\u00e4hungen und\/oder Schmerzen im Unterleib?<\/li>\n<li>Hatten Sie in der Vergangenheit Hautprobleme wie Nesselsucht, Hautausschl\u00e4ge, Akne, Ekzeme, Psoriasis oder Dermatitis?<\/li>\n<li>Leiden Sie h\u00e4ufig unter Kopfschmerzen, Hirnnebel, Angstzust\u00e4nden oder neigen Sie zu explosiven Wutausbr\u00fcchen?<\/li>\n<li>Err\u00f6ten Sie, bekommen Sie Schwei\u00dfausbr\u00fcche oder neigen Sie zu hei\u00dfen H\u00e4nden und F\u00fc\u00dfen?<\/li>\n<li>Verschlimmern sich Ihre Symptome, wenn Sie Alkohol konsumieren? Oder wenn Sie Kreuzbl\u00fctler und andere schwefelhaltige Lebensmittel wie Knoblauch, Zwiebeln und Eier essen?<\/li>\n<\/ul>\n<p>Wenn Sie einige dieser Fragen mit &#8222;ja&#8220; beantworten k\u00f6nnen, haben Sie m\u00f6glicherweise Probleme mit der Verarbeitung von Schwefel und sollten die folgenden Schritte in Betracht ziehen.<\/p>\n<h3><strong>Schritt 1: Verringerung schwefelhaltiger Lebensmittel<\/strong><\/h3>\n<p>Ich empfehle meinen Patienten in der Regel, die folgenden schwefelhaltigen Lebensmittel f\u00fcr mindestens zwei Wochen aus ihrer Ern\u00e4hrung zu streichen:<\/p>\n<ul>\n<li>Knoblauch<\/li>\n<li>Zwiebeln<\/li>\n<li>Kraut<\/li>\n<li>Gr\u00fcnkohl<\/li>\n<li>Gr\u00fcner Kohl<\/li>\n<li>Blumenkohl<\/li>\n<li>Rosenkohl<\/li>\n<li>Brokkoli<\/li>\n<li>Rucola<\/li>\n<li>Alle Trockenfr\u00fcchte<\/li>\n<li>Essig<\/li>\n<li>Alkoholische Getr\u00e4nke<\/li>\n<li>Molkereiprodukte und Eier<\/li>\n<li>Soja<\/li>\n<li>Gro\u00dfe Mengen an mageren tierischen Produkten (fettreicheres Fleisch und Fisch sind vorzuziehen, da sie weniger Schwefel enthalten)<\/li>\n<\/ul>\n<h3><strong>Schritt 2: Vermeiden Sie schwefelhaltige Nahrungserg\u00e4nzungsmittel<\/strong><\/h3>\n<p>Stellen Sie in Verbindung mit einer Ern\u00e4hrungsumstellung sicher, dass Sie die folgenden Nahrungserg\u00e4nzungsmittel nicht mehr einnehmen:<\/p>\n<ul>\n<li>Knoblauch-Extrakte<\/li>\n<li>N-Acetylcystein (NAC)<\/li>\n<li>Glutathion<\/li>\n<li>Taurin<\/li>\n<li>Cystein<\/li>\n<li>Methionin<\/li>\n<li>Chondroitin-Sulfat und MSM<\/li>\n<li>DMSA\/DMSO<\/li>\n<li>Mariendistel<\/li>\n<li>Alpha-Lipons\u00e4ure<\/li>\n<li>Epson-Salzb\u00e4der<\/li>\n<\/ul>\n<h3><strong>Schritt 3: Unterst\u00fctzen Sie Ihren Transsulfurierungsweg<\/strong><\/h3>\n<p>Die folgenden Nahrungserg\u00e4nzungsmittel sind hilfreich, um Ihren Schwefelweg zu unterst\u00fctzen:<\/p>\n<ul>\n<li>B12 (in Form von Hydroxocobalamin)<\/li>\n<li>Molybd\u00e4n (fl\u00fcssige Version verwenden und sehr langsam beginnen)<\/li>\n<li>Calcium\/Magnesium-Butyrat<\/li>\n<\/ul>\n<h3><strong>Schritt 4: Identifizieren Sie die Grundursache<\/strong><\/h3>\n<p>Wie bereits erw\u00e4hnt, k\u00f6nnen Sie einige genetische Mutationen haben, die Ihren K\u00f6rper daran hindern, Schwefel effizient zu verarbeiten und auszuscheiden. Ich empfehle Ihnen, einen qualifizierten Arzt aufzusuchen, der Ihnen helfen kann, eventuelle Gendefekte zu erkennen. Einige wichtige genetische Marker, auf die man achten sollte, sind:<\/p>\n<ul>\n<li>CBS\/CSE<\/li>\n<li>SUOX<\/li>\n<li>NOS<\/li>\n<li>MTHFR<\/li>\n<\/ul>\n<p>Ihr Arzt kann sich daf\u00fcr entscheiden, Ihren Schwefelgehalt durch einen Urintest zu bestimmen, und er kann Ihnen auch empfehlen, auf Schwermetalle, chemische Empfindlichkeiten und Dysbiose zu testen. In manchen F\u00e4llen haben die Ern\u00e4hrungsempfehlungen nur eine leicht positive Wirkung. In diesem Fall empfehle ich Ihnen zus\u00e4tzlich, Lebensmittel mit einem hohen Anteil an Thiolen (Verbindungen, die zweiwertigen Schwefel enthalten) zu meiden<sup data-preserve-html-node=\"true\">.9<\/sup> Sobald Sie sich ein klares Bild von Ihrem aktuellen Gesundheitszustand gemacht haben, kann Ihr Arzt gezielte Behandlungsprotokolle durchf\u00fchren, um die Ursache Ihres Problems anzugehen.<\/p>\n<hr>\n<p>Referenzen<\/p>\n<h6>Lindeberg S, et al. Eine pal\u00e4olithische Di\u00e4t verbessert die Glukosetoleranz bei Personen mit isch\u00e4mischer Herzerkrankung st\u00e4rker als eine mediterrane Di\u00e4t.Diabetologia, 2007.  [http:\/\/www .ncbi.nlm.nih.gov\/pubmed\/17583796]<\/h6>\n<h6>Osterdahl M, et al. Auswirkungen einer kurzfristigen Intervention mit einer pal\u00e4olithischen Ern\u00e4hrung bei gesunden Freiwilligen. Europ\u00e4ische Zeitschrift f\u00fcr klinische Ern\u00e4hrung, 2008.  [http:\/\/www .ncbi.nlm.nih.gov\/pubmed\/17522610]<\/h6>\n<h6>Jonsson T, et al. G\u00fcnstige Auswirkungen einer pal\u00e4olithischen Ern\u00e4hrung auf kardiovaskul\u00e4re Risikofaktoren bei Typ-2-Diabetes: eine randomisierte Cross-over-Pilotstudie. Kardiovaskul\u00e4re Diabetologie, 2009.  [http:\/\/www .ncbi.nlm.nih.gov\/pubmed\/19604407]<\/h6>\n<h6>Frassetto, et al. Metabolische und physiologische Verbesserungen durch den Verzehr einer pal\u00e4olithischen, j\u00e4ger- und sammlerartigen Ern\u00e4hrung. Europ\u00e4ische Zeitschrift f\u00fcr klinische Ern\u00e4hrung, 2009.  [http:\/\/www .ncbi.nlm.nih.gov\/pubmed\/19209185]<\/h6>\n<h6>Ryberg, et al. Eine pal\u00e4olithische Di\u00e4t hat starke gewebespezifische Auswirkungen auf die ektopische Fettablagerung bei fettleibigen postmenopausalen Frauen. Zeitschrift f\u00fcr Innere Medizin, 2013.  [http:\/\/www .ncbi.nlm.nih.gov\/pubmed\/23414424]<\/h6>\n<h6>Marcel E. Nimni, Bo Han und Fabiola Cordoba. Bekommen wir genug Schwefel in unserer Ern\u00e4hrung? Ern\u00e4hrung und Stoffwechsel 2007.  [http:\/\/www .nutritionandmetabolism.com\/content\/4\/1\/24 \/]<\/h6>\n<h6>Greg Nigh, ND, LAc Maria Zilka, NTP. Erkennen und Behandeln von Schwefelreaktionen und den damit verbundenen Symptomen. Biotics Research Seminar, 20.07.2015.<\/h6>\n<h6>Clark. &#8222;Schwefelhaltige Lebensmittel (Thiole)&#8220;. Livingnetworkcoza. Web. 8 Sept. 2015.  [http:\/\/www .livingnetwork.co.za\/chelationnetwork\/food\/high-sulfur-sulphur-food-list \/]<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>In den letzten Jahren hat die Paleo-Di\u00e4t als Mittel zur Verbesserung der allgemeinen Gesundheit viel Aufmerksamkeit erhalten. Es gibt zahlreiche anekdotische Belege f\u00fcr Verbesserungen bei Patienten, die sich nach einer Paleo-Di\u00e4t oder der restriktiveren Autoimmun-Paleo-Di\u00e4t (AIP) ern\u00e4hren.&nbsp;Weniger h\u00e4ufig h\u00f6rt man, dass manche Menschen negative Auswirkungen oder eine Verschlimmerung ihrer Symptome durch eine Paleo- oder AIP-Di\u00e4t erfahren. Es scheint kontraintuitiv, dass eine gesunde Ern\u00e4hrung mit einem hohen Anteil an Kreuzbl\u00fctlern wie Gr\u00fcnkohl, Kohl und Brokkoli in Kombination mit hochwertigen Proteinen und Fetten dazu f\u00fchren kann, dass man sich schlechter f\u00fchlt. Warum ist das der Fall?<\/p>\n","protected":false},"author":1,"featured_media":1042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[309],"tags":[335,334,336,321,337,339,338,340],"class_list":["post-1119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magen-darm-probleme","tag-blahungen","tag-kopfschmerzen","tag-kreuzblutengewachse","tag-palao","tag-schwefel","tag-schwefelempfindlichkeit","tag-schwefelunvertraglichkeit","tag-transsulfurierung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang | Optimal Brain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang | Optimal Brain\" \/>\n<meta property=\"og:description\" content=\"In den letzten Jahren hat die Paleo-Di\u00e4t als Mittel zur Verbesserung der allgemeinen Gesundheit viel Aufmerksamkeit erhalten. Es gibt zahlreiche anekdotische Belege f\u00fcr Verbesserungen bei Patienten, die sich nach einer Paleo-Di\u00e4t oder der restriktiveren Autoimmun-Paleo-Di\u00e4t (AIP) ern\u00e4hren.&nbsp;Weniger h\u00e4ufig h\u00f6rt man, dass manche Menschen negative Auswirkungen oder eine Verschlimmerung ihrer Symptome durch eine Paleo- oder AIP-Di\u00e4t erfahren. Es scheint kontraintuitiv, dass eine gesunde Ern\u00e4hrung mit einem hohen Anteil an Kreuzbl\u00fctlern wie Gr\u00fcnkohl, Kohl und Brokkoli in Kombination mit hochwertigen Proteinen und Fetten dazu f\u00fchren kann, dass man sich schlechter f\u00fchlt. Warum ist das der Fall?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/\" \/>\n<meta property=\"og:site_name\" content=\"Optimal Brain\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DoctorAuer\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-18T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/optimalbrain.ch\/wp-content\/uploads\/2015\/09\/paleo-diet-not-working.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Auer DC, IFMCP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Auer DC, IFMCP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/\"},\"author\":{\"name\":\"Daniel Auer DC, IFMCP\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#\\\/schema\\\/person\\\/2e41c8acc0cd73135f4aa3a602bba26d\"},\"headline\":\"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang\",\"datePublished\":\"2015-09-18T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/\"},\"wordCount\":1080,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optimalbrain.ch\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/paleo-diet-not-working.jpg\",\"keywords\":[\"Bl\u00e4hungen\",\"Kopfschmerzen\",\"Kreuzbl\u00fctengew\u00e4chse\",\"Pal\u00e4o\",\"Schwefel\",\"Schwefelempfindlichkeit\",\"Schwefelunvertr\u00e4glichkeit\",\"Transsulfurierung\"],\"articleSection\":[\"Magen-Darm-Probleme\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/\",\"url\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/\",\"name\":\"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang | Optimal Brain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/optimalbrain.ch\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/paleo-diet-not-working.jpg\",\"datePublished\":\"2015-09-18T16:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#primaryimage\",\"url\":\"https:\\\/\\\/optimalbrain.ch\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/paleo-diet-not-working.jpg\",\"contentUrl\":\"https:\\\/\\\/optimalbrain.ch\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/paleo-diet-not-working.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/\",\"name\":\"Optimal Brain\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#organization\",\"name\":\"Optimal Brain\",\"url\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/optimalbrain.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Optimal-Brain-switzerland.png\",\"contentUrl\":\"http:\\\/\\\/optimalbrain.ch\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Optimal-Brain-switzerland.png\",\"width\":300,\"height\":83,\"caption\":\"Optimal Brain\"},\"image\":{\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DoctorAuer\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/optimalbrain.ch\\\/de\\\/#\\\/schema\\\/person\\\/2e41c8acc0cd73135f4aa3a602bba26d\",\"name\":\"Daniel Auer DC, IFMCP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9a3847a1be8eb6f3bf970e952c11e4e146118436efe2ad8d60112d443a8ba2e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9a3847a1be8eb6f3bf970e952c11e4e146118436efe2ad8d60112d443a8ba2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9a3847a1be8eb6f3bf970e952c11e4e146118436efe2ad8d60112d443a8ba2e?s=96&d=mm&r=g\",\"caption\":\"Daniel Auer DC, IFMCP\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang | Optimal Brain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/","og_locale":"de_DE","og_type":"article","og_title":"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang | Optimal Brain","og_description":"In den letzten Jahren hat die Paleo-Di\u00e4t als Mittel zur Verbesserung der allgemeinen Gesundheit viel Aufmerksamkeit erhalten. Es gibt zahlreiche anekdotische Belege f\u00fcr Verbesserungen bei Patienten, die sich nach einer Paleo-Di\u00e4t oder der restriktiveren Autoimmun-Paleo-Di\u00e4t (AIP) ern\u00e4hren.&nbsp;Weniger h\u00e4ufig h\u00f6rt man, dass manche Menschen negative Auswirkungen oder eine Verschlimmerung ihrer Symptome durch eine Paleo- oder AIP-Di\u00e4t erfahren. Es scheint kontraintuitiv, dass eine gesunde Ern\u00e4hrung mit einem hohen Anteil an Kreuzbl\u00fctlern wie Gr\u00fcnkohl, Kohl und Brokkoli in Kombination mit hochwertigen Proteinen und Fetten dazu f\u00fchren kann, dass man sich schlechter f\u00fchlt. Warum ist das der Fall?","og_url":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/","og_site_name":"Optimal Brain","article_publisher":"https:\/\/www.facebook.com\/DoctorAuer","article_published_time":"2015-09-18T16:00:00+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/optimalbrain.ch\/wp-content\/uploads\/2015\/09\/paleo-diet-not-working.jpg","type":"image\/jpeg"}],"author":"Daniel Auer DC, IFMCP","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel Auer DC, IFMCP","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#article","isPartOf":{"@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/"},"author":{"name":"Daniel Auer DC, IFMCP","@id":"https:\/\/optimalbrain.ch\/de\/#\/schema\/person\/2e41c8acc0cd73135f4aa3a602bba26d"},"headline":"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang","datePublished":"2015-09-18T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/"},"wordCount":1080,"commentCount":0,"publisher":{"@id":"https:\/\/optimalbrain.ch\/de\/#organization"},"image":{"@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#primaryimage"},"thumbnailUrl":"https:\/\/optimalbrain.ch\/wp-content\/uploads\/2015\/09\/paleo-diet-not-working.jpg","keywords":["Bl\u00e4hungen","Kopfschmerzen","Kreuzbl\u00fctengew\u00e4chse","Pal\u00e4o","Schwefel","Schwefelempfindlichkeit","Schwefelunvertr\u00e4glichkeit","Transsulfurierung"],"articleSection":["Magen-Darm-Probleme"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/","url":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/","name":"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang | Optimal Brain","isPartOf":{"@id":"https:\/\/optimalbrain.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#primaryimage"},"image":{"@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#primaryimage"},"thumbnailUrl":"https:\/\/optimalbrain.ch\/wp-content\/uploads\/2015\/09\/paleo-diet-not-working.jpg","datePublished":"2015-09-18T16:00:00+00:00","breadcrumb":{"@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#primaryimage","url":"https:\/\/optimalbrain.ch\/wp-content\/uploads\/2015\/09\/paleo-diet-not-working.jpg","contentUrl":"https:\/\/optimalbrain.ch\/wp-content\/uploads\/2015\/09\/paleo-diet-not-working.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/optimalbrain.ch\/de\/funktioniert-die-paleo-diaet-nicht-erforschung-der-schwefelintoleranz-als-moeglicher-zusammenhang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/optimalbrain.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Funktioniert die Paleo-Di\u00e4t nicht? Erforschung der Schwefelintoleranz als m\u00f6glicher Zusammenhang"}]},{"@type":"WebSite","@id":"https:\/\/optimalbrain.ch\/de\/#website","url":"https:\/\/optimalbrain.ch\/de\/","name":"Optimal Brain","description":"","publisher":{"@id":"https:\/\/optimalbrain.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/optimalbrain.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/optimalbrain.ch\/de\/#organization","name":"Optimal Brain","url":"https:\/\/optimalbrain.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/optimalbrain.ch\/de\/#\/schema\/logo\/image\/","url":"http:\/\/optimalbrain.ch\/wp-content\/uploads\/2021\/05\/Optimal-Brain-switzerland.png","contentUrl":"http:\/\/optimalbrain.ch\/wp-content\/uploads\/2021\/05\/Optimal-Brain-switzerland.png","width":300,"height":83,"caption":"Optimal Brain"},"image":{"@id":"https:\/\/optimalbrain.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DoctorAuer"]},{"@type":"Person","@id":"https:\/\/optimalbrain.ch\/de\/#\/schema\/person\/2e41c8acc0cd73135f4aa3a602bba26d","name":"Daniel Auer DC, IFMCP","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d9a3847a1be8eb6f3bf970e952c11e4e146118436efe2ad8d60112d443a8ba2e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9a3847a1be8eb6f3bf970e952c11e4e146118436efe2ad8d60112d443a8ba2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9a3847a1be8eb6f3bf970e952c11e4e146118436efe2ad8d60112d443a8ba2e?s=96&d=mm&r=g","caption":"Daniel Auer DC, IFMCP"}}]}},"_links":{"self":[{"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/posts\/1119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/comments?post=1119"}],"version-history":[{"count":0,"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/posts\/1119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/media?parent=1119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/categories?post=1119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/optimalbrain.ch\/de\/wp-json\/wp\/v2\/tags?post=1119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}